{"id":36,"count":1,"description":"","link":"https:\/\/www.captaintag.live\/outdoor-life\/topics\/outdoor-camp\/hammock\/","name":"\u30cf\u30f3\u30e2\u30c3\u30af","slug":"hammock","taxonomy":"category","parent":1,"meta":[],"_links":{"self":[{"href":"https:\/\/www.captaintag.live\/outdoor-life\/wp-json\/wp\/v2\/categories\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.captaintag.live\/outdoor-life\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.captaintag.live\/outdoor-life\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.captaintag.live\/outdoor-life\/wp-json\/wp\/v2\/categories\/1"}],"wp:post_type":[{"href":"https:\/\/www.captaintag.live\/outdoor-life\/wp-json\/wp\/v2\/posts?categories=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}